{"id":81297,"date":"2026-03-17T10:13:42","date_gmt":"2026-03-17T14:13:42","guid":{"rendered":"https:\/\/connecticut-bailbonds.com\/?page_id=81297"},"modified":"2026-03-20T13:26:00","modified_gmt":"2026-03-20T17:26:00","slug":"en-connecticut-una-arraignment-es-la-primera-comparecencia-formal-del-acusado-en-el-tribunal-en-esta-audiencia-el-acusado-es-informado-de-los-cargos-que-se-le-imputan-se-le-pregunta-si-entiende","status":"publish","type":"page","link":"https:\/\/connecticut-bailbonds.com\/es\/what-is-an-arraignment-in-connecticut-court\/","title":{"rendered":"\u00bfQu\u00e9 es una lectura de cargos en un tribunal de Connecticut?"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"81297\" class=\"elementor elementor-81297\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2eed4b2f elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2eed4b2f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6406e1f1\" data-id=\"6406e1f1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-40b3f28f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40b3f28f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-414e93f6\" data-id=\"414e93f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-547d9422 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"547d9422\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es una lectura de cargos en la corte de Connecticut?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b4ca6f6\" data-id=\"6b4ca6f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f9bd34a elementor-tablet-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"6f9bd34a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Consulta Gratuita<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48ec8b07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48ec8b07\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a8f0dd7\" data-id=\"3a8f0dd7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21eb6df1 elementor-widget elementor-widget-text-editor\" data-id=\"21eb6df1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Enfrentar cargos criminales puede resultar confuso y estresante, especialmente si es la primera vez que lidias con el sistema judicial. En Connecticut, uno de los primeros pasos en un caso criminal es la lectura de cargos. Esta primera comparecencia ante el tribunal es importante porque es donde el tribunal aborda formalmente los cargos y describe lo que suceder\u00e1 a continuaci\u00f3n. Saber en qu\u00e9 consiste una lectura de cargos puede hacer que el proceso se sienta un poco m\u00e1s manejable.<\/p><h2>Entendiendo una imputaci\u00f3n formal en Connecticut<\/h2><p>Una lectura de cargos suele ser la primera vez que un acusado comparece ante un juez despu\u00e9s de un arresto o de recibir una citaci\u00f3n judicial penal. En esta audiencia, el tribunal inicia el proceso legal formal y explica el caso a un nivel b\u00e1sico.<\/p><p>Durante una audiencia de lectura de cargos, generalmente puedes esperar lo siguiente:<\/p><ul><li>Se presentan los cargos. El juez se asegura de que est\u00e9s informado de las acusaciones presentadas en tu contra.<\/li><li>Se presenta una declaraci\u00f3n. Es posible que se le pida que responda a los cargos declar\u00e1ndose culpable, no culpable o sin admitir culpa. A menudo es aconsejable hablar con un abogado antes de tomar esa decisi\u00f3n.<\/li><li>La fianza est\u00e1 bajo revisi\u00f3n. La corte puede decidir si permanecer\u00e1 detenido o ser\u00e1 liberado, y bajo qu\u00e9 condiciones de fianza.<\/li><li>Se explican tus derechos. El juez podr\u00eda repasar derechos importantes, incluido el derecho a un abogado y el derecho a guardar silencio.<\/li><\/ul><h2>\u00bfQu\u00e9 sucede durante una lectura de cargos en Connecticut?<\/h2><p>Aunque cada caso es diferente, la mayor\u00eda de las audiencias de lectura de cargos en Connecticut siguen una estructura similar. Comprender el proceso general puede ayudarte a prepararte para el d\u00eda.<\/p><ul><li>Llega temprano. Date tiempo suficiente para pasar por seguridad y registrarte antes de que te llamen.<\/li><li>Traiga identificaci\u00f3n. Es posible que necesite presentar una identificaci\u00f3n con foto v\u00e1lida al llegar al tribunal.<\/li><li>Pres\u00e9ntate ante el juez. Cuando se llame tu caso, te presentar\u00e1s ante el juez mientras el tribunal aborde los cargos y los temas relacionados.<\/li><li>Escuche los cargos. El juez identificar\u00e1 el o los delitos involucrados en su caso. Si algo no est\u00e1 claro, es importante pedir una aclaraci\u00f3n.<\/li><li>Declare su inocencia o culpabilidad. El tribunal le preguntar\u00e1 c\u00f3mo se declara. Este es un paso crucial en el proceso, por lo que la orientaci\u00f3n legal puede ser muy valiosa.<\/li><li>Determinaci\u00f3n de fianza. Si la fianza no se ha fijado todav\u00eda, el juez puede decidir el monto y cualquier condici\u00f3n para la liberaci\u00f3n.<\/li><li>Reciba su pr\u00f3xima fecha de corte. Antes de irse, normalmente le indicar\u00e1n cu\u00e1ndo debe regresar y si hay otros pasos que debe seguir.<\/li><\/ul><h2>C\u00f3mo prepararse para su primera comparecencia ante el tribunal<\/h2><p>Entrar a la corte preparado puede ayudar a reducir el estr\u00e9s y permitirte manejar el proceso de manera m\u00e1s efectiva. Unos cuantos pasos sencillos pueden marcar la diferencia.<\/p><ul><li>Hable con un abogado lo antes posible. Un abogado penalista de Connecticut puede ayudarlo a comprender sus opciones, explicar los posibles resultados y defenderlo durante el proceso de fianza y lectura de cargos.<\/li><li>Re\u00fana documentos \u00fatiles. Elementos como comprobante de empleo, comprobante de residencia u otros registros pueden ser \u00fatiles si se est\u00e1 discutiendo una fianza.<\/li><li>V\u00edstete respetuosamente. Tu apariencia en la corte es importante. Elige ropa limpia y apropiada que demuestre respeto por el lugar.<\/li><li>Sea cort\u00e9s y atento. Dir\u00edjase al juez y al personal de la corte con respeto, y preste mucha atenci\u00f3n a lo que se diga durante la audiencia.<\/li><li>Mantente organizado. Anota la fecha de tu pr\u00f3xima comparecencia ante el tribunal y cualquier instrucci\u00f3n dada por el tribunal para no perder plazos importantes.<\/li><li>Mant\u00e9n un contacto cercano con tu abogado. Una buena comunicaci\u00f3n puede ayudarte a mantenerte informado y evitar errores a medida que tu caso avanza.<\/li><\/ul><h2>D\u00f3nde encontrar informaci\u00f3n sobre los tribunales de Connecticut<\/h2><p>Si necesita informaci\u00f3n de contacto de los tribunales o informaci\u00f3n general sobre los tribunales de Connecticut, la mejor fuente es la Rama Judicial oficial de Connecticut. La ubicaci\u00f3n de los tribunales, los n\u00fameros de tel\u00e9fono y la informaci\u00f3n de programaci\u00f3n tambi\u00e9n pueden estar disponibles a trav\u00e9s de directorios oficiales de tribunales y recursos p\u00fablicos de los tribunales. Dado que los detalles de los tribunales pueden cambiar, siempre es mejor verificar la informaci\u00f3n directamente con el tribunal espec\u00edfico que maneja el caso.<\/p><h2>Ayuda con la fianza durante el proceso judicial<\/h2><p>Para muchas familias, una de las mayores preocupaciones en torno a una lectura de cargos es si un ser querido puede ser liberado r\u00e1pidamente. Las decisiones sobre la fianza a menudo ocurren al principio del caso, y el tiempo es importante. <a href=\"https:\/\/connecticut-bailbonds.com\/es\/\">Fianzas Connecticut<\/a> ayuda a los clientes a comprender el proceso de liberaci\u00f3n, a manejar las inquietudes sobre fianzas y a obtener asistencia r\u00e1pida cuando m\u00e1s la necesitan.<\/p><h2>Avanzando despu\u00e9s de una lectura de cargos<\/h2><p>Una lectura de cargos es solo el comienzo de un caso penal, pero es un primer paso muy importante. Comprender lo que sucede en la corte, prepararse con anticipaci\u00f3n y obtener el apoyo adecuado puede ayudarlo a avanzar con mayor confianza. Cuando surjan preguntas sobre la fianza o la liberaci\u00f3n, Connecticut Bail Bonds est\u00e1 aqu\u00ed para brindar ayuda confiable durante todo el proceso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71bf417e elementor-tablet-align-center elementor-mobile-align-left elementor-align-center elementor-widget elementor-widget-button\" data-id=\"71bf417e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"\/es\/contacto\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Consulta Gratuita<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36297972 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36297972\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40e1d1c1\" data-id=\"40e1d1c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65f258fa elementor-widget elementor-widget-heading\" data-id=\"65f258fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c1reas de servicio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-194c6cd elementor-widget elementor-widget-text-editor\" data-id=\"194c6cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/ubicaciones\/fianzas-del-condado-de-hartford\/\"><span class=\"elementor-icon-list-text\">Fianzas del Condado de Hartford<\/span><\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/ubicaciones\/fianzas-del-condado-de-fairfield\/\"><span class=\"elementor-icon-list-text\">Fianzas del Condado de Fairfield<\/span><\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/ubicaciones\/fianzas-del-condado-de-litchfield\/\"><span class=\"elementor-icon-list-text\">Fianzas de Litchfield County<\/span><\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/ubicaciones\/fianzas-del-condado-de-middlesex\/\"><span class=\"elementor-icon-list-text\">Fianzas del Condado de Middlesex<\/span><\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/ubicaciones\/fianzas-del-condado-de-new-london\/\"><span class=\"elementor-icon-list-text\">Fianzas del Condado de New London<\/span><\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/ubicaciones\/fianza-en-el-condado-de-tolland\/\"><span class=\"elementor-icon-list-text\">Fianzas del Condado de Tolland<\/span><\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/ubicaciones\/fianzas-en-el-condado-de-windham\/\"><span class=\"elementor-icon-list-text\">Fianzas de Windham County<\/span><\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/ubicaciones\/fianzas-del-condado-de-new-haven\/\"><span class=\"elementor-icon-list-text\">Fianzas del Condado de New Haven<\/span><\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20821097 elementor-widget elementor-widget-heading\" data-id=\"20821097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00e1s informaci\u00f3n sobre servicios de fianzas\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bc50e7 elementor-widget elementor-widget-text-editor\" data-id=\"8bc50e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/blog\/cuanto-tiempo-se-tarda-en-salir-de-la-carcel-despues-de-pagar-la-fianza\/\">\u00bfCu\u00e1nto tiempo se tarda en salir de la c\u00e1rcel despu\u00e9s de pagar la fianza?<\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/para-sacar-a-alguien-de-la-carcel-bajo-fianza-en-connecticut-generalmente-se-necesita-lo-siguiente1-la-cantidad-de-la-fianza-el-juez-establecera-una-cantidad-de-dinero-que-debe-pagarse-o-as\/\">\u00bfQu\u00e9 se necesita para sacar a alguien de la c\u00e1rcel en Connecticut?<\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/comisionado-de-fianzas-vs-juez-en-connecticut\/\">Comisionado de Fianzas vs. Juez en Connecticut<\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/entendiendo-las-ordenes-de-arresto-en-connecticut\/\">Entendiendo las \u00f3rdenes de captura en Connecticut<\/a><\/li>\n<li><a href=\"https:\/\/connecticut-bailbonds.com\/es\/una-compania-de-fianzas-puede-negarte-el-servicio\/\">\u00bfPuede una compa\u00f1\u00eda de fianzas negarse a trabajar contigo?<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>What Is An Arraignment In Connecticut Court? Free Consultation Facing criminal charges can feel confusing and stressful, especially if this is your first time dealing with the court system. In Connecticut, one of the earliest steps in a criminal case is the arraignment. This first court appearance is important because it is where the court [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":30869,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"rank_math_focus_keyword":"","rank_math_description":"","footnotes":""},"class_list":["post-81297","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/connecticut-bailbonds.com\/es\/wp-json\/wp\/v2\/pages\/81297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/connecticut-bailbonds.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/connecticut-bailbonds.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/connecticut-bailbonds.com\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/connecticut-bailbonds.com\/es\/wp-json\/wp\/v2\/comments?post=81297"}],"version-history":[{"count":5,"href":"https:\/\/connecticut-bailbonds.com\/es\/wp-json\/wp\/v2\/pages\/81297\/revisions"}],"predecessor-version":[{"id":81481,"href":"https:\/\/connecticut-bailbonds.com\/es\/wp-json\/wp\/v2\/pages\/81297\/revisions\/81481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/connecticut-bailbonds.com\/es\/wp-json\/wp\/v2\/media\/30869"}],"wp:attachment":[{"href":"https:\/\/connecticut-bailbonds.com\/es\/wp-json\/wp\/v2\/media?parent=81297"}],"curies":[{"name":"bien jugado","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}